{"id":6230,"date":"2022-07-28T17:47:42","date_gmt":"2022-07-28T15:47:42","guid":{"rendered":"http:\/\/dev.claret.cat\/editorial\/editorial-males-herbes\/"},"modified":"2022-07-28T17:47:42","modified_gmt":"2022-07-28T15:47:42","slug":"editorial-males-herbes","status":"publish","type":"editorial","link":"https:\/\/www.claret.cat\/es\/editorial\/editorial-males-herbes\/","title":{"rendered":"Editorial Males Herbes"},"template":"","class_list":["post-6230","editorial","type-editorial","status-publish","hentry"],"acf":{"libros":"52"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/editorial\/6230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/editorial"}],"about":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/types\/editorial"}],"wp:attachment":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media?parent=6230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}