{"id":6250,"date":"2022-07-28T17:48:10","date_gmt":"2022-07-28T15:48:10","guid":{"rendered":"http:\/\/dev.claret.cat\/editorial\/eumo-editorial-valenciano-catalan\/"},"modified":"2022-07-28T17:48:10","modified_gmt":"2022-07-28T15:48:10","slug":"eumo-editorial-valenciano-catalan","status":"publish","type":"editorial","link":"https:\/\/www.claret.cat\/es\/editorial\/eumo-editorial-valenciano-catalan\/","title":{"rendered":"EUMO EDITORIAL-VALENCIANO\/CATALAN-"},"template":"","class_list":["post-6250","editorial","type-editorial","status-publish","hentry"],"acf":{"libros":"78"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/editorial\/6250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/editorial"}],"about":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/types\/editorial"}],"wp:attachment":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media?parent=6250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}