{"id":6289,"date":"2022-07-28T17:48:59","date_gmt":"2022-07-28T15:48:59","guid":{"rendered":"http:\/\/dev.claret.cat\/editorial\/libros-disney\/"},"modified":"2022-07-28T17:48:59","modified_gmt":"2022-07-28T15:48:59","slug":"libros-disney","status":"publish","type":"editorial","link":"https:\/\/www.claret.cat\/es\/editorial\/libros-disney\/","title":{"rendered":"LIBROS DISNEY"},"template":"","class_list":["post-6289","editorial","type-editorial","status-publish","hentry"],"acf":{"libros":"905"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/editorial\/6289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/editorial"}],"about":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/types\/editorial"}],"wp:attachment":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media?parent=6289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}