{"id":122878,"date":"2022-10-12T16:54:53","date_gmt":"2022-10-12T14:54:53","guid":{"rendered":"http:\/\/dev.claret.cat\/producte\/la-gran-competicio\/"},"modified":"2025-01-31T17:08:33","modified_gmt":"2025-01-31T16:08:33","slug":"la-gran-competicio-9788424665807","status":"publish","type":"product","link":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/","title":{"rendered":"LA GRAN COMPETICI\u00d3"},"content":{"rendered":"<p>Hi haur\u00e0 encanteris. Hi haur\u00e0 batalles. I hi haur\u00e0 una quantitat perillosa de sabates precioses. <\/p>\n<p>Hi ha un m\u00f3n on viuen les bruixes, baixant per les canonades de l&#8217;aig\u00fcera. <\/p>\n<p>La Tiga no t\u00e9 ni idea de tot aix\u00f2. O com a m\u00ednim era aix\u00ed fins que una fada fabulosa i la porta a Ciudad Ritzi per qu\u00e8 competeixi a Guerres de bruixes, una competici\u00f3 plena d&#8217;endevinalles! I bruixes extranyes! I una sabata enorme. <\/p>\n<p>La Tiga ser\u00e0 capa\u00e7 de guanyar? Dif\u00edcilment.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POUNDER, SIB\u00c9AL<\/p>\n","protected":false},"featured_media":122879,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[90,540],"product_tag":[],"class_list":["post-122878","product","type-product","status-publish","has-post-thumbnail","product_cat-altres","product_cat-otros","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":{"autor":"POUNDER, SIB\u00c9AL","codart":"842466580","libros-coleccion":"Bruixes a la moda","ediciones":"1","encuadernacion":"R\u00fastica","fecha_de_publicacion":"01\/11\/2019","novedad":"1","paginas":"286","subtitulo":"","orden":"0","portada":"0","idioma":"cat","editorial":[{"ID":148189,"post_author":"3","post_date":"2022-10-14 11:56:19","post_date_gmt":"2022-10-14 09:56:19","post_content":"","post_title":"GALERA, EDITORIAL","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"galera-editorial","to_ping":"","pinged":"","post_modified":"2022-10-14 11:56:19","post_modified_gmt":"2022-10-14 09:56:19","post_content_filtered":"","post_parent":0,"guid":"http:\/\/dev.claret.cat\/editorial\/galera-editorial\/","menu_order":0,"post_type":"editorial","post_mime_type":"","comment_count":"0","filter":"raw"}],"autores-libros":[{"ID":169446,"post_author":"3","post_date":"2022-10-14 22:27:18","post_date_gmt":"2022-10-14 20:27:18","post_content":"","post_title":"SIB\u00c9AL POUNDER","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"sibeal-pounder","to_ping":"","pinged":"","post_modified":"2022-10-14 22:27:18","post_modified_gmt":"2022-10-14 20:27:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/dev.claret.cat\/autor\/sibeal-pounder\/","menu_order":0,"post_type":"autor","post_mime_type":"","comment_count":"0","filter":"raw"}]},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"LA GRAN COMPETICI\u00d3 de POUNDER, SIB\u00c9AL disponible a\/en Llibreria Claret.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Llibreria Claret - Llibreria religiosa a Barcelona\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"LA GRAN COMPETICI\u00d3 - POUNDER, SIB\u00c9AL 9788424665807 | Llibreria Claret\" \/>\n\t\t<meta property=\"og:description\" content=\"LA GRAN COMPETICI\u00d3 de POUNDER, SIB\u00c9AL disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-10-12T14:54:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-01-31T16:08:33+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:title\" content=\"LA GRAN COMPETICI\u00d3 - POUNDER, SIB\u00c9AL 9788424665807 | Llibreria Claret\" \/>\n\t\t<meta name=\"twitter:description\" content=\"LA GRAN COMPETICI\u00d3 de POUNDER, SIB\u00c9AL disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"position\":3,\"name\":\"CAT\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/#listItem\",\"name\":\"Altres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/#listItem\",\"position\":4,\"name\":\"Altres\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/#listItem\",\"name\":\"Altres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/#listItem\",\"position\":5,\"name\":\"Altres\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#listItem\",\"name\":\"LA GRAN COMPETICI\\u00d3\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/#listItem\",\"name\":\"Altres\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#listItem\",\"position\":6,\"name\":\"LA GRAN COMPETICI\\u00d3\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/#listItem\",\"name\":\"Altres\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#itempage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/\",\"name\":\"LA GRAN COMPETICI\\u00d3 - POUNDER, SIB\\u00c9AL 9788424665807 | Llibreria Claret\",\"description\":\"LA GRAN COMPETICI\\u00d3 de POUNDER, SIB\\u00c9AL disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9788424665807.jpg\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#mainImage\",\"width\":225,\"height\":330,\"caption\":\"9788424665807.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#mainImage\"},\"datePublished\":\"2022-10-12T16:54:53+02:00\",\"dateModified\":\"2025-01-31T17:08:33+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\",\"name\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"email\":\"comunicacio@claret.cat\",\"telephone\":\"+34933010887\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/logo-claret-es.png\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#organizationLogo\",\"width\":195,\"height\":79},\"image\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LlibreriaClaret\",\"https:\\\/\\\/twitter.com\\\/LlibreriaClaret\",\"https:\\\/\\\/www.instagram.com\\\/llibreriaclaret\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@llibreriaclaret\",\"https:\\\/\\\/www.youtube.com\\\/@llibreriaclaret\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Editorial_Claret\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#webpage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/\",\"name\":\"LA GRAN COMPETICI\\u00d3 - POUNDER, SIB\\u00c9AL 9788424665807 | Llibreria Claret\",\"description\":\"LA GRAN COMPETICI\\u00d3 de POUNDER, SIB\\u00c9AL disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9788424665807.jpg\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#mainImage\",\"width\":225,\"height\":330,\"caption\":\"9788424665807.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/la-gran-competicio-9788424665807\\\/#mainImage\"},\"datePublished\":\"2022-10-12T16:54:53+02:00\",\"dateModified\":\"2025-01-31T17:08:33+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"name\":\"Llibreria Claret Barcelona\",\"alternateName\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>LA GRAN COMPETICI\u00d3 - POUNDER, SIB\u00c9AL 9788424665807 | Llibreria Claret<\/title>\n\n","aioseo_head_json":{"title":"LA GRAN COMPETICI\u00d3 - POUNDER, SIB\u00c9AL 9788424665807 | Llibreria Claret","description":"LA GRAN COMPETICI\u00d3 de POUNDER, SIB\u00c9AL disponible a\/en Llibreria Claret.","canonical_url":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.claret.cat\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","position":2,"name":"Botiga","item":"https:\/\/www.claret.cat\/?page_id=16","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","position":3,"name":"CAT","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/#listItem","name":"Altres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/#listItem","position":4,"name":"Altres","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/#listItem","name":"Altres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/#listItem","position":5,"name":"Altres","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#listItem","name":"LA GRAN COMPETICI\u00d3"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/#listItem","name":"Altres"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#listItem","position":6,"name":"LA GRAN COMPETICI\u00d3","previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/#listItem","name":"Altres"}}]},{"@type":"ItemPage","@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#itempage","url":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/","name":"LA GRAN COMPETICI\u00d3 - POUNDER, SIB\u00c9AL 9788424665807 | Llibreria Claret","description":"LA GRAN COMPETICI\u00d3 de POUNDER, SIB\u00c9AL disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9788424665807.jpg","@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#mainImage","width":225,"height":330,"caption":"9788424665807.jpg"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#mainImage"},"datePublished":"2022-10-12T16:54:53+02:00","dateModified":"2025-01-31T17:08:33+01:00"},{"@type":"Organization","@id":"https:\/\/www.claret.cat\/es\/#organization","name":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","url":"https:\/\/www.claret.cat\/es\/","email":"comunicacio@claret.cat","telephone":"+34933010887","logo":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/logo-claret-es.png","@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#organizationLogo","width":195,"height":79},"image":{"@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/LlibreriaClaret","https:\/\/twitter.com\/LlibreriaClaret","https:\/\/www.instagram.com\/llibreriaclaret\/","https:\/\/www.tiktok.com\/@llibreriaclaret","https:\/\/www.youtube.com\/@llibreriaclaret","https:\/\/ca.wikipedia.org\/wiki\/Editorial_Claret"]},{"@type":"WebPage","@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#webpage","url":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/","name":"LA GRAN COMPETICI\u00d3 - POUNDER, SIB\u00c9AL 9788424665807 | Llibreria Claret","description":"LA GRAN COMPETICI\u00d3 de POUNDER, SIB\u00c9AL disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9788424665807.jpg","@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#mainImage","width":225,"height":330,"caption":"9788424665807.jpg"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/#mainImage"},"datePublished":"2022-10-12T16:54:53+02:00","dateModified":"2025-01-31T17:08:33+01:00"},{"@type":"WebSite","@id":"https:\/\/www.claret.cat\/es\/#website","url":"https:\/\/www.claret.cat\/es\/","name":"Llibreria Claret Barcelona","alternateName":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.claret.cat\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Llibreria Claret - Llibreria religiosa a Barcelona","og:type":"article","og:title":"LA GRAN COMPETICI\u00d3 - POUNDER, SIB\u00c9AL 9788424665807 | Llibreria Claret","og:description":"LA GRAN COMPETICI\u00d3 de POUNDER, SIB\u00c9AL disponible a\/en Llibreria Claret.","og:url":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/","og:image":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","og:image:secure_url":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","article:published_time":"2022-10-12T14:54:53+00:00","article:modified_time":"2025-01-31T16:08:33+00:00","article:publisher":"https:\/\/www.facebook.com\/LlibreriaClaret","twitter:card":"summary_large_image","twitter:site":"@LlibreriaClaret","twitter:title":"LA GRAN COMPETICI\u00d3 - POUNDER, SIB\u00c9AL 9788424665807 | Llibreria Claret","twitter:description":"LA GRAN COMPETICI\u00d3 de POUNDER, SIB\u00c9AL disponible a\/en Llibreria Claret.","twitter:image":"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg"},"aioseo_meta_data":{"post_id":"122878","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-11-29 18:30:05","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-12-19 21:27:40","updated":"2025-11-29 18:30:05","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/?page_id=16\" title=\"Botiga\">Botiga<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/\" title=\"CAT\">CAT<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/\" title=\"Altres\">Altres<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/\" title=\"Altres\">Altres<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tLA GRAN COMPETICI\u00d3\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.claret.cat\/es\/"},{"label":"Botiga","link":"https:\/\/www.claret.cat\/?page_id=16"},{"label":"CAT","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/"},{"label":"Altres","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/"},{"label":"Altres","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/"},{"label":"LA GRAN COMPETICI\u00d3","link":"https:\/\/www.claret.cat\/es\/libro\/la-gran-competicio-9788424665807\/"}],"_links":{"self":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product\/122878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media\/122879"}],"wp:attachment":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media?parent=122878"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_brand?post=122878"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_cat?post=122878"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_tag?post=122878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}