{"id":123379,"date":"2022-10-12T17:02:36","date_gmt":"2022-10-12T15:02:36","guid":{"rendered":"http:\/\/dev.claret.cat\/producte\/les-mascotes\/"},"modified":"2024-04-11T11:01:16","modified_gmt":"2024-04-11T09:01:16","slug":"les-mascotes-9789876378079","status":"publish","type":"product","link":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/","title":{"rendered":"LES MASCOTES"},"content":{"rendered":"<p>Un encantador llibre pensat perqu\u00e8 els m\u00e9s petits juguin amb els sons i les textures de les p\u00e0gines i a partir de la combinaci\u00f3 de tots dos associ\u00efn amb les il\u00b7lustracions dels diferents animals de companyia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>, ELS EDITORS DE CATAPULTA<\/p>\n","protected":false},"featured_media":123380,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[90,540],"product_tag":[],"class_list":["post-123379","product","type-product","status-publish","has-post-thumbnail","product_cat-altres","product_cat-otros","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":{"editorial":[{"ID":8224,"post_author":"3","post_date":"2022-09-30 09:21:12","post_date_gmt":"2022-09-30 07:21:12","post_content":"","post_title":"CATAPULTA EDICIONES","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"catapulta-ediciones","to_ping":"","pinged":"","post_modified":"2022-09-30 09:21:12","post_modified_gmt":"2022-09-30 07:21:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/dev.claret.cat\/editorial\/catapulta-ediciones\/","menu_order":0,"post_type":"editorial","post_mime_type":"","comment_count":"0","filter":"raw"}],"autores-libros":[{"ID":5443,"post_author":"3","post_date":"2022-07-28 17:24:04","post_date_gmt":"2022-07-28 15:24:04","post_content":"","post_title":"ELS EDITORS DE CATAPULTA","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"els-editors-de-catapulta","to_ping":"","pinged":"","post_modified":"2022-07-28 17:24:04","post_modified_gmt":"2022-07-28 15:24:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/dev.claret.cat\/autor\/els-editors-de-catapulta\/","menu_order":0,"post_type":"autor","post_mime_type":"","comment_count":"0","filter":"raw"}],"autor":", ELS EDITORS DE CATAPULTA","codart":"987637807","libros-coleccion":"TOCA I ESCOLTA","ediciones":"1","encuadernacion":"Carton\u00e9","fecha_de_publicacion":"01\/11\/2019","novedad":"1","paginas":"12","subtitulo":"","orden":"0","portada":"0","idioma":"cat"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\/en Llibreria Claret.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Llibreria Claret - Llibreria religiosa a Barcelona\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret\" \/>\n\t\t<meta property=\"og:description\" content=\"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-10-12T15:02:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-11T09:01:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:title\" content=\"LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret\" \/>\n\t\t<meta name=\"twitter:description\" content=\"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"position\":3,\"name\":\"CAT\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/#listItem\",\"name\":\"Altres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/#listItem\",\"position\":4,\"name\":\"Altres\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/#listItem\",\"name\":\"Altres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/#listItem\",\"position\":5,\"name\":\"Altres\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#listItem\",\"name\":\"LES MASCOTES\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/#listItem\",\"name\":\"Altres\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#listItem\",\"position\":6,\"name\":\"LES MASCOTES\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/#listItem\",\"name\":\"Altres\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#itempage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/\",\"name\":\"LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret\",\"description\":\"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9789876378079.png\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#mainImage\",\"width\":225,\"height\":225,\"caption\":\"9789876378079.png\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#mainImage\"},\"datePublished\":\"2022-10-12T17:02:36+02:00\",\"dateModified\":\"2024-04-11T11:01:16+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\",\"name\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"email\":\"comunicacio@claret.cat\",\"telephone\":\"+34933010887\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/logo-claret-es.png\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#organizationLogo\",\"width\":195,\"height\":79},\"image\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LlibreriaClaret\",\"https:\\\/\\\/twitter.com\\\/LlibreriaClaret\",\"https:\\\/\\\/www.instagram.com\\\/llibreriaclaret\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@llibreriaclaret\",\"https:\\\/\\\/www.youtube.com\\\/@llibreriaclaret\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Editorial_Claret\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#webpage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/\",\"name\":\"LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret\",\"description\":\"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9789876378079.png\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#mainImage\",\"width\":225,\"height\":225,\"caption\":\"9789876378079.png\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/les-mascotes-9789876378079\\\/#mainImage\"},\"datePublished\":\"2022-10-12T17:02:36+02:00\",\"dateModified\":\"2024-04-11T11:01:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"name\":\"Llibreria Claret Barcelona\",\"alternateName\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret<\/title>\n\n","aioseo_head_json":{"title":"LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret","description":"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\/en Llibreria Claret.","canonical_url":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.claret.cat\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","position":2,"name":"Botiga","item":"https:\/\/www.claret.cat\/?page_id=16","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","position":3,"name":"CAT","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/#listItem","name":"Altres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/#listItem","position":4,"name":"Altres","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/#listItem","name":"Altres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/#listItem","position":5,"name":"Altres","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#listItem","name":"LES MASCOTES"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/#listItem","name":"Altres"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#listItem","position":6,"name":"LES MASCOTES","previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/#listItem","name":"Altres"}}]},{"@type":"ItemPage","@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#itempage","url":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/","name":"LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret","description":"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9789876378079.png","@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#mainImage","width":225,"height":225,"caption":"9789876378079.png"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#mainImage"},"datePublished":"2022-10-12T17:02:36+02:00","dateModified":"2024-04-11T11:01:16+02:00"},{"@type":"Organization","@id":"https:\/\/www.claret.cat\/es\/#organization","name":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","url":"https:\/\/www.claret.cat\/es\/","email":"comunicacio@claret.cat","telephone":"+34933010887","logo":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/logo-claret-es.png","@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#organizationLogo","width":195,"height":79},"image":{"@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/LlibreriaClaret","https:\/\/twitter.com\/LlibreriaClaret","https:\/\/www.instagram.com\/llibreriaclaret\/","https:\/\/www.tiktok.com\/@llibreriaclaret","https:\/\/www.youtube.com\/@llibreriaclaret","https:\/\/ca.wikipedia.org\/wiki\/Editorial_Claret"]},{"@type":"WebPage","@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#webpage","url":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/","name":"LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret","description":"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9789876378079.png","@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#mainImage","width":225,"height":225,"caption":"9789876378079.png"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/#mainImage"},"datePublished":"2022-10-12T17:02:36+02:00","dateModified":"2024-04-11T11:01:16+02:00"},{"@type":"WebSite","@id":"https:\/\/www.claret.cat\/es\/#website","url":"https:\/\/www.claret.cat\/es\/","name":"Llibreria Claret Barcelona","alternateName":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.claret.cat\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Llibreria Claret - Llibreria religiosa a Barcelona","og:type":"article","og:title":"LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret","og:description":"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\/en Llibreria Claret.","og:url":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/","og:image":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","og:image:secure_url":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","article:published_time":"2022-10-12T15:02:36+00:00","article:modified_time":"2024-04-11T09:01:16+00:00","article:publisher":"https:\/\/www.facebook.com\/LlibreriaClaret","twitter:card":"summary_large_image","twitter:site":"@LlibreriaClaret","twitter:title":"LES MASCOTES - , ELS EDITORS DE CATAPULTA 9789876378079 | Llibreria Claret","twitter:description":"LES MASCOTES de , ELS EDITORS DE CATAPULTA disponible a\/en Llibreria Claret.","twitter:image":"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg"},"aioseo_meta_data":{"post_id":"123379","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-11-29 19:27:21","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-12-19 21:43:22","updated":"2025-11-29 19:27:21","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/?page_id=16\" title=\"Botiga\">Botiga<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/\" title=\"CAT\">CAT<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/\" title=\"Altres\">Altres<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/\" title=\"Altres\">Altres<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tLES MASCOTES\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.claret.cat\/es\/"},{"label":"Botiga","link":"https:\/\/www.claret.cat\/?page_id=16"},{"label":"CAT","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/"},{"label":"Altres","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/"},{"label":"Altres","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/"},{"label":"LES MASCOTES","link":"https:\/\/www.claret.cat\/es\/libro\/les-mascotes-9789876378079\/"}],"_links":{"self":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product\/123379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media\/123380"}],"wp:attachment":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media?parent=123379"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_brand?post=123379"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_cat?post=123379"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_tag?post=123379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}