{"id":221601,"date":"2022-10-20T16:01:59","date_gmt":"2022-10-20T14:01:59","guid":{"rendered":"http:\/\/dev.claret.cat\/producte\/teologia-de-la-revelacion\/"},"modified":"2025-11-24T18:35:58","modified_gmt":"2025-11-24T17:35:58","slug":"teologia-de-la-revelacion-9788430119516","status":"publish","type":"product","link":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/","title":{"rendered":"TEOLOG\u00cdA DE LA REVELACI\u00d3N"},"content":{"rendered":"<p>Dios ha dejado a un lado su silencio y en Cristo ha manifestado al hombre su designio inaudito de establecer con \u00e9l una comuni\u00f3n vital. Y es en esto que consiste la revelaci\u00f3n, hecho decisivo para la fe y fundamento de toda investigaci\u00f3n teol\u00f3gica. De ah\u00ed que su estudio sea una prioridad tanto desde un punto de vista apolog\u00e9tico, que reflexiona sobre el hecho y los signos de la revelaci\u00f3n, como desde una mirada dogm\u00e1tica, que busca descubrir su naturaleza, sus dimensiones y su profundidad.<\/p>\n<p>Este libro quiere contribuir a la dogm\u00e1tica de la revelaci\u00f3n. Busca la inteligencia de la fe apoy\u00e1ndose en la Escritura y en la tradici\u00f3n, en la predicaci\u00f3n y en la liturgia de la Iglesia. Da respuesta adem\u00e1s a las inquietudes de el momento act\u00faal, que desea devolver a la palabra de Dios el puesto de honor que le pertenece en la fe y en la vida cristiana, y conecta con las preocupaciones ecum\u00e9nicas, el poner en el centro esta Palabra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATOURELLE, REN\u00c9<\/p>\n","protected":false},"featured_media":1068123,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[415,277,342,76],"product_tag":[],"class_list":["post-221601","product","type-product","status-publish","has-post-thumbnail","product_cat-dogmatica-teologia-1_espiritualidad","product_cat-dogmatica","product_cat-teologia-1_espiritualidad","product_cat-teologia","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":{"autor":"LATOURELLE, REN\u00c9","codart":"843011951","libros-coleccion":"","ediciones":"10","encuadernacion":"R\u00fastica","fecha_de_publicacion":"28\/11\/2016","novedad":"1","paginas":"584","subtitulo":"","orden":"0","portada":"0","idioma":"spa","editorial":[{"ID":6364,"post_author":"3","post_date":"2022-07-28 17:50:36","post_date_gmt":"2022-07-28 15:50:36","post_content":"","post_title":"S\u00edgueme","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"sigueme","to_ping":"","pinged":"","post_modified":"2022-07-28 17:50:36","post_modified_gmt":"2022-07-28 15:50:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/dev.claret.cat\/editorial\/sigueme\/","menu_order":0,"post_type":"editorial","post_mime_type":"","comment_count":"0","filter":"raw"}],"autores-libros":[{"ID":283787,"post_author":"3","post_date":"2022-12-10 01:43:52","post_date_gmt":"2022-12-10 00:43:52","post_content":"","post_title":"RENE LATOURELLE","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"rene-latourelle","to_ping":"","pinged":"","post_modified":"2022-12-10 01:43:52","post_modified_gmt":"2022-12-10 00:43:52","post_content_filtered":"","post_parent":0,"guid":"http:\/\/dev.claret.cat\/autor\/rene-latourelle\/","menu_order":0,"post_type":"autor","post_mime_type":"","comment_count":"0","filter":"raw"}],"booktrailer":"","resenas":""},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"TEOLOG\u00cdA DE LA REVELACI\u00d3N de LATOURELLE, REN\u00c9 disponible a\/en Llibreria Claret.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Llibreria Claret - Llibreria religiosa a Barcelona\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"TEOLOG\u00cdA DE LA REVELACI\u00d3N - LATOURELLE, REN\u00c9 9788430119516 | Llibreria Claret\" \/>\n\t\t<meta property=\"og:description\" content=\"TEOLOG\u00cdA DE LA REVELACI\u00d3N de LATOURELLE, REN\u00c9 disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-10-20T14:01:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-24T17:35:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:title\" content=\"TEOLOG\u00cdA DE LA REVELACI\u00d3N - LATOURELLE, REN\u00c9 9788430119516 | Llibreria Claret\" \/>\n\t\t<meta name=\"twitter:description\" content=\"TEOLOG\u00cdA DE LA REVELACI\u00d3N de LATOURELLE, REN\u00c9 disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"position\":3,\"name\":\"CAT\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/#listItem\",\"name\":\"Espiritualitat\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/#listItem\",\"position\":4,\"name\":\"Espiritualitat\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/teologia\\\/#listItem\",\"name\":\"Teologia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/teologia\\\/#listItem\",\"position\":5,\"name\":\"Teologia\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/teologia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/teologia\\\/dogmatica\\\/#listItem\",\"name\":\"Dogm\\u00e0tica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/#listItem\",\"name\":\"Espiritualitat\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/teologia\\\/dogmatica\\\/#listItem\",\"position\":6,\"name\":\"Dogm\\u00e0tica\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/teologia\\\/dogmatica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#listItem\",\"name\":\"TEOLOG\\u00cdA DE LA REVELACI\\u00d3N\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/teologia\\\/#listItem\",\"name\":\"Teologia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#listItem\",\"position\":7,\"name\":\"TEOLOG\\u00cdA DE LA REVELACI\\u00d3N\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/1_espiritualitat\\\/teologia\\\/dogmatica\\\/#listItem\",\"name\":\"Dogm\\u00e0tica\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#itempage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/\",\"name\":\"TEOLOG\\u00cdA DE LA REVELACI\\u00d3N - LATOURELLE, REN\\u00c9 9788430119516 | Llibreria Claret\",\"description\":\"TEOLOG\\u00cdA DE LA REVELACI\\u00d3N de LATOURELLE, REN\\u00c9 disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9788430119516-4.jpg\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#mainImage\",\"width\":250,\"height\":389,\"caption\":\"9788430119516.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#mainImage\"},\"datePublished\":\"2022-10-20T16:01:59+02:00\",\"dateModified\":\"2025-11-24T18:35:58+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\",\"name\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"email\":\"comunicacio@claret.cat\",\"telephone\":\"+34933010887\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/logo-claret-es.png\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#organizationLogo\",\"width\":195,\"height\":79},\"image\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LlibreriaClaret\",\"https:\\\/\\\/twitter.com\\\/LlibreriaClaret\",\"https:\\\/\\\/www.instagram.com\\\/llibreriaclaret\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@llibreriaclaret\",\"https:\\\/\\\/www.youtube.com\\\/@llibreriaclaret\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Editorial_Claret\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#webpage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/\",\"name\":\"TEOLOG\\u00cdA DE LA REVELACI\\u00d3N - LATOURELLE, REN\\u00c9 9788430119516 | Llibreria Claret\",\"description\":\"TEOLOG\\u00cdA DE LA REVELACI\\u00d3N de LATOURELLE, REN\\u00c9 disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9788430119516-4.jpg\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#mainImage\",\"width\":250,\"height\":389,\"caption\":\"9788430119516.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/teologia-de-la-revelacion-9788430119516\\\/#mainImage\"},\"datePublished\":\"2022-10-20T16:01:59+02:00\",\"dateModified\":\"2025-11-24T18:35:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"name\":\"Llibreria Claret Barcelona\",\"alternateName\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>TEOLOG\u00cdA DE LA REVELACI\u00d3N - LATOURELLE, REN\u00c9 9788430119516 | Llibreria Claret<\/title>\n\n","aioseo_head_json":{"title":"TEOLOG\u00cdA DE LA REVELACI\u00d3N - LATOURELLE, REN\u00c9 9788430119516 | Llibreria Claret","description":"TEOLOG\u00cdA DE LA REVELACI\u00d3N de LATOURELLE, REN\u00c9 disponible a\/en Llibreria Claret.","canonical_url":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.claret.cat\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","position":2,"name":"Botiga","item":"https:\/\/www.claret.cat\/?page_id=16","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","position":3,"name":"CAT","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/#listItem","name":"Espiritualitat"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/#listItem","position":4,"name":"Espiritualitat","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/#listItem","name":"Teologia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/#listItem","position":5,"name":"Teologia","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/dogmatica\/#listItem","name":"Dogm\u00e0tica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/#listItem","name":"Espiritualitat"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/dogmatica\/#listItem","position":6,"name":"Dogm\u00e0tica","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/dogmatica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#listItem","name":"TEOLOG\u00cdA DE LA REVELACI\u00d3N"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/#listItem","name":"Teologia"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#listItem","position":7,"name":"TEOLOG\u00cdA DE LA REVELACI\u00d3N","previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/dogmatica\/#listItem","name":"Dogm\u00e0tica"}}]},{"@type":"ItemPage","@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#itempage","url":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/","name":"TEOLOG\u00cdA DE LA REVELACI\u00d3N - LATOURELLE, REN\u00c9 9788430119516 | Llibreria Claret","description":"TEOLOG\u00cdA DE LA REVELACI\u00d3N de LATOURELLE, REN\u00c9 disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9788430119516-4.jpg","@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#mainImage","width":250,"height":389,"caption":"9788430119516.jpg"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#mainImage"},"datePublished":"2022-10-20T16:01:59+02:00","dateModified":"2025-11-24T18:35:58+01:00"},{"@type":"Organization","@id":"https:\/\/www.claret.cat\/es\/#organization","name":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","url":"https:\/\/www.claret.cat\/es\/","email":"comunicacio@claret.cat","telephone":"+34933010887","logo":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/logo-claret-es.png","@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#organizationLogo","width":195,"height":79},"image":{"@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/LlibreriaClaret","https:\/\/twitter.com\/LlibreriaClaret","https:\/\/www.instagram.com\/llibreriaclaret\/","https:\/\/www.tiktok.com\/@llibreriaclaret","https:\/\/www.youtube.com\/@llibreriaclaret","https:\/\/ca.wikipedia.org\/wiki\/Editorial_Claret"]},{"@type":"WebPage","@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#webpage","url":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/","name":"TEOLOG\u00cdA DE LA REVELACI\u00d3N - LATOURELLE, REN\u00c9 9788430119516 | Llibreria Claret","description":"TEOLOG\u00cdA DE LA REVELACI\u00d3N de LATOURELLE, REN\u00c9 disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9788430119516-4.jpg","@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#mainImage","width":250,"height":389,"caption":"9788430119516.jpg"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/#mainImage"},"datePublished":"2022-10-20T16:01:59+02:00","dateModified":"2025-11-24T18:35:58+01:00"},{"@type":"WebSite","@id":"https:\/\/www.claret.cat\/es\/#website","url":"https:\/\/www.claret.cat\/es\/","name":"Llibreria Claret Barcelona","alternateName":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.claret.cat\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Llibreria Claret - Llibreria religiosa a Barcelona","og:type":"article","og:title":"TEOLOG\u00cdA DE LA REVELACI\u00d3N - LATOURELLE, REN\u00c9 9788430119516 | Llibreria Claret","og:description":"TEOLOG\u00cdA DE LA REVELACI\u00d3N de LATOURELLE, REN\u00c9 disponible a\/en Llibreria Claret.","og:url":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/","og:image":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","og:image:secure_url":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","article:published_time":"2022-10-20T14:01:59+00:00","article:modified_time":"2025-11-24T17:35:58+00:00","article:publisher":"https:\/\/www.facebook.com\/LlibreriaClaret","twitter:card":"summary_large_image","twitter:site":"@LlibreriaClaret","twitter:title":"TEOLOG\u00cdA DE LA REVELACI\u00d3N - LATOURELLE, REN\u00c9 9788430119516 | Llibreria Claret","twitter:description":"TEOLOG\u00cdA DE LA REVELACI\u00d3N de LATOURELLE, REN\u00c9 disponible a\/en Llibreria Claret.","twitter:image":"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg"},"aioseo_meta_data":{"post_id":"221601","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-11-24 17:37:03","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-12-21 14:58:41","updated":"2025-11-24 17:37:03","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/?page_id=16\" title=\"Botiga\">Botiga<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/\" title=\"CAT\">CAT<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/\" title=\"Espiritualitat\">Espiritualitat<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/\" title=\"Teologia\">Teologia<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/dogmatica\/\" title=\"Dogm\u00e0tica\">Dogm\u00e0tica<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tTEOLOG\u00cdA DE LA REVELACI\u00d3N\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.claret.cat\/es\/"},{"label":"Botiga","link":"https:\/\/www.claret.cat\/?page_id=16"},{"label":"CAT","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/"},{"label":"Espiritualitat","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/"},{"label":"Teologia","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/"},{"label":"Dogm\u00e0tica","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/1_espiritualitat\/teologia\/dogmatica\/"},{"label":"TEOLOG\u00cdA DE LA REVELACI\u00d3N","link":"https:\/\/www.claret.cat\/es\/libro\/teologia-de-la-revelacion-9788430119516\/"}],"_links":{"self":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product\/221601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media\/1068123"}],"wp:attachment":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media?parent=221601"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_brand?post=221601"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_cat?post=221601"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_tag?post=221601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}