{"id":404492,"date":"2023-02-28T00:02:23","date_gmt":"2023-02-27T23:02:23","guid":{"rendered":"https:\/\/www.claret.cat\/llibre\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/"},"modified":"2023-02-28T00:02:35","modified_gmt":"2023-02-27T23:02:35","slug":"obras-completas-san-jeronimo-xaepistolario-i-9788479149772","status":"publish","type":"product","link":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/","title":{"rendered":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I"},"content":{"rendered":"<p>  El epistolario de san Jer\u00f3nimo, que comprende un centenar y medio de cartas, constituye una clave imprescindible para acercarse a la interioridad del personaje. Las cartas son como una gu\u00eda que invita y a la vez conduce a trav\u00e9s de la experiencia \u00edntima de alguien que, dirigi\u00e9ndose a personas particulares, sabe dar a lo escrito el valor universal de lo privado. Por lo que respecta a los contenidos, Jer\u00f3nimo cultiva cuatro campos fundamentales; el de la amistad, el exeg\u00e9tico, el dogm\u00e1tico y el asc\u00e9tico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN JERONIMO<\/p>\n","protected":false},"featured_media":404493,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[90,540],"product_tag":[],"class_list":["post-404492","product","type-product","status-publish","has-post-thumbnail","product_cat-altres","product_cat-otros","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":{"autor":"SAN JERONIMO","codart":"847914977","libros-coleccion":"","ediciones":"1","encuadernacion":"Carton\u00e9","fecha_de_publicacion":"01\/03\/2013","novedad":"0","paginas":"991","subtitulo":"","orden":"999","portada":"0","idioma":"spa","editorial":[{"ID":6139,"post_author":"3","post_date":"2022-07-28 17:45:43","post_date_gmt":"2022-07-28 15:45:43","post_content":"","post_title":"BAC","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"bac","to_ping":"","pinged":"","post_modified":"2022-07-28 17:45:43","post_modified_gmt":"2022-07-28 15:45:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/dev.claret.cat\/editorial\/bac\/","menu_order":0,"post_type":"editorial","post_mime_type":"","comment_count":"0","filter":"raw"}],"autores-libros":[{"ID":404486,"post_author":"3","post_date":"2023-02-28 00:00:14","post_date_gmt":"2023-02-27 23:00:14","post_content":"","post_title":"SAN JER\u00d3NIMO","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"san-jeronimo-2","to_ping":"","pinged":"","post_modified":"2023-02-28 00:00:14","post_modified_gmt":"2023-02-27 23:00:14","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.claret.cat\/autor\/san-jeronimo-2\/","menu_order":0,"post_type":"autor","post_mime_type":"","comment_count":"0","filter":"raw"}]},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\/en Llibreria Claret.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Llibreria Claret - Llibreria religiosa a Barcelona\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret\" \/>\n\t\t<meta property=\"og:description\" content=\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-02-27T23:02:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-02-27T23:02:35+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:title\" content=\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret\" \/>\n\t\t<meta name=\"twitter:description\" content=\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"position\":3,\"name\":\"CAT\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/#listItem\",\"name\":\"Altres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/#listItem\",\"position\":4,\"name\":\"Altres\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/#listItem\",\"name\":\"Altres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/#listItem\",\"position\":5,\"name\":\"Altres\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#listItem\",\"name\":\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/#listItem\",\"name\":\"Altres\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#listItem\",\"position\":6,\"name\":\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/5_altres\\\/altres\\\/#listItem\",\"name\":\"Altres\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#itempage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/\",\"name\":\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret\",\"description\":\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9788479149772.jpg\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#mainImage\",\"width\":318,\"height\":499,\"caption\":\"9788479149772.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#mainImage\"},\"datePublished\":\"2023-02-28T00:02:23+01:00\",\"dateModified\":\"2023-02-28T00:02:35+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\",\"name\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"email\":\"comunicacio@claret.cat\",\"telephone\":\"+34933010887\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/logo-claret-es.png\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#organizationLogo\",\"width\":195,\"height\":79},\"image\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LlibreriaClaret\",\"https:\\\/\\\/twitter.com\\\/LlibreriaClaret\",\"https:\\\/\\\/www.instagram.com\\\/llibreriaclaret\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@llibreriaclaret\",\"https:\\\/\\\/www.youtube.com\\\/@llibreriaclaret\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Editorial_Claret\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#webpage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/\",\"name\":\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret\",\"description\":\"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9788479149772.jpg\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#mainImage\",\"width\":318,\"height\":499,\"caption\":\"9788479149772.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\\\/#mainImage\"},\"datePublished\":\"2023-02-28T00:02:23+01:00\",\"dateModified\":\"2023-02-28T00:02:35+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"name\":\"Llibreria Claret Barcelona\",\"alternateName\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret<\/title>\n\n","aioseo_head_json":{"title":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret","description":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\/en Llibreria Claret.","canonical_url":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.claret.cat\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","position":2,"name":"Botiga","item":"https:\/\/www.claret.cat\/?page_id=16","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","position":3,"name":"CAT","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/#listItem","name":"Altres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/#listItem","position":4,"name":"Altres","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/#listItem","name":"Altres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/#listItem","position":5,"name":"Altres","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#listItem","name":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/#listItem","name":"Altres"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#listItem","position":6,"name":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I","previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/#listItem","name":"Altres"}}]},{"@type":"ItemPage","@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#itempage","url":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/","name":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret","description":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9788479149772.jpg","@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#mainImage","width":318,"height":499,"caption":"9788479149772.jpg"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#mainImage"},"datePublished":"2023-02-28T00:02:23+01:00","dateModified":"2023-02-28T00:02:35+01:00"},{"@type":"Organization","@id":"https:\/\/www.claret.cat\/es\/#organization","name":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","url":"https:\/\/www.claret.cat\/es\/","email":"comunicacio@claret.cat","telephone":"+34933010887","logo":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/logo-claret-es.png","@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#organizationLogo","width":195,"height":79},"image":{"@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/LlibreriaClaret","https:\/\/twitter.com\/LlibreriaClaret","https:\/\/www.instagram.com\/llibreriaclaret\/","https:\/\/www.tiktok.com\/@llibreriaclaret","https:\/\/www.youtube.com\/@llibreriaclaret","https:\/\/ca.wikipedia.org\/wiki\/Editorial_Claret"]},{"@type":"WebPage","@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#webpage","url":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/","name":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret","description":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9788479149772.jpg","@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#mainImage","width":318,"height":499,"caption":"9788479149772.jpg"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/#mainImage"},"datePublished":"2023-02-28T00:02:23+01:00","dateModified":"2023-02-28T00:02:35+01:00"},{"@type":"WebSite","@id":"https:\/\/www.claret.cat\/es\/#website","url":"https:\/\/www.claret.cat\/es\/","name":"Llibreria Claret Barcelona","alternateName":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.claret.cat\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Llibreria Claret - Llibreria religiosa a Barcelona","og:type":"article","og:title":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret","og:description":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\/en Llibreria Claret.","og:url":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/","og:image":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","og:image:secure_url":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","article:published_time":"2023-02-27T23:02:23+00:00","article:modified_time":"2023-02-27T23:02:35+00:00","article:publisher":"https:\/\/www.facebook.com\/LlibreriaClaret","twitter:card":"summary_large_image","twitter:site":"@LlibreriaClaret","twitter:title":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I - SAN JERONIMO 9788479149772 | Llibreria Claret","twitter:description":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I de SAN JERONIMO disponible a\/en Llibreria Claret.","twitter:image":"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg"},"aioseo_meta_data":{"post_id":"404492","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-12-01 17:27:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2023-05-31 01:48:13","updated":"2025-12-01 17:27:04"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/?page_id=16\" title=\"Botiga\">Botiga<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/\" title=\"CAT\">CAT<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/\" title=\"Altres\">Altres<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/\" title=\"Altres\">Altres<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tOBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.claret.cat\/es\/"},{"label":"Botiga","link":"https:\/\/www.claret.cat\/?page_id=16"},{"label":"CAT","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/"},{"label":"Altres","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/"},{"label":"Altres","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/5_altres\/altres\/"},{"label":"OBRAS COMPLETAS SAN JERONIMO Xa.EPISTOLARIO I","link":"https:\/\/www.claret.cat\/es\/libro\/obras-completas-san-jeronimo-xaepistolario-i-9788479149772\/"}],"_links":{"self":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product\/404492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media\/404493"}],"wp:attachment":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media?parent=404492"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_brand?post=404492"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_cat?post=404492"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_tag?post=404492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}