{"id":973221,"date":"2024-07-03T16:40:46","date_gmt":"2024-07-03T14:40:46","guid":{"rendered":"https:\/\/www.claret.cat\/llibre\/el-pez-jugueton-9788411821520\/"},"modified":"2025-04-22T12:20:37","modified_gmt":"2025-04-22T10:20:37","slug":"el-pez-jugueton-9788411821520","status":"publish","type":"product","link":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/","title":{"rendered":"EL PEZ JUGUET\u00d3N"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>WISE, GRAHAM<\/p>\n","protected":false},"featured_media":973222,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[131,361],"product_tag":[],"class_list":["post-973221","product","type-product","status-publish","has-post-thumbnail","product_cat-contes-per-infants-0-6-anys","product_cat-cuentos-para-ninos-0-6-anos","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":{"autor":"WISE, GRAHAM","codart":"841182152","libros-coleccion":"FORA DE COL.LECCI\u00d3","ediciones":"1","encuadernacion":"Carpeta","fecha_de_publicacion":"01\/07\/2024","novedad":"1","paginas":"12","subtitulo":"","orden":"0","portada":"0","idioma":"cat","editorial":[{"ID":951118,"post_author":"3","post_date":"2024-02-08 13:48:06","post_date_gmt":"2024-02-08 12:48:06","post_content":"","post_title":"SM EDICIONES","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"sm-ediciones","to_ping":"","pinged":"","post_modified":"2024-02-08 13:48:06","post_modified_gmt":"2024-02-08 12:48:06","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.claret.cat\/editorial\/sm-ediciones\/","menu_order":0,"post_type":"editorial","post_mime_type":"","comment_count":"0","filter":"raw"}],"booktrailer":"","resenas":""},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"EL PEZ JUGUET\u00d3N de WISE, GRAHAM disponible a\/en Llibreria Claret.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Llibreria Claret - Llibreria religiosa a Barcelona\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"EL PEZ JUGUET\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret\" \/>\n\t\t<meta property=\"og:description\" content=\"EL PEZ JUGUET\u00d3N de WISE, GRAHAM disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-07-03T14:40:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-04-22T10:20:37+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@LlibreriaClaret\" \/>\n\t\t<meta name=\"twitter:title\" content=\"EL PEZ JUGUET\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret\" \/>\n\t\t<meta name=\"twitter:description\" content=\"EL PEZ JUGUET\u00d3N de WISE, GRAHAM disponible a\/en Llibreria Claret.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"position\":3,\"name\":\"CAT\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/#listItem\",\"name\":\"Infantil \\\/ Juvenil\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/?page_id=16#listItem\",\"name\":\"Botiga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/#listItem\",\"position\":4,\"name\":\"Infantil \\\/ Juvenil\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/infantil\\\/#listItem\",\"name\":\"Infantil\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/#listItem\",\"name\":\"CAT\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/infantil\\\/#listItem\",\"position\":5,\"name\":\"Infantil\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/infantil\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/infantil\\\/contes-per-infants-0-6-anys\\\/#listItem\",\"name\":\"0 - 6 anys\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/#listItem\",\"name\":\"Infantil \\\/ Juvenil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/infantil\\\/contes-per-infants-0-6-anys\\\/#listItem\",\"position\":6,\"name\":\"0 - 6 anys\",\"item\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/infantil\\\/contes-per-infants-0-6-anys\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#listItem\",\"name\":\"EL PEZ JUGUET\\u00d3N\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/infantil\\\/#listItem\",\"name\":\"Infantil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#listItem\",\"position\":7,\"name\":\"EL PEZ JUGUET\\u00d3N\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/categoria-producto\\\/cat\\\/3_infantil-juvenil\\\/infantil\\\/contes-per-infants-0-6-anys\\\/#listItem\",\"name\":\"0 - 6 anys\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#itempage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/\",\"name\":\"EL PEZ JUGUET\\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret\",\"description\":\"EL PEZ JUGUET\\u00d3N de WISE, GRAHAM disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9788411821520.jpg\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#mainImage\",\"width\":250,\"height\":240,\"caption\":\"9788411821520.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#mainImage\"},\"datePublished\":\"2024-07-03T16:40:46+02:00\",\"dateModified\":\"2025-04-22T12:20:37+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\",\"name\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"email\":\"comunicacio@claret.cat\",\"telephone\":\"+34933010887\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/logo-claret-es.png\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#organizationLogo\",\"width\":195,\"height\":79},\"image\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LlibreriaClaret\",\"https:\\\/\\\/twitter.com\\\/LlibreriaClaret\",\"https:\\\/\\\/www.instagram.com\\\/llibreriaclaret\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@llibreriaclaret\",\"https:\\\/\\\/www.youtube.com\\\/@llibreriaclaret\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Editorial_Claret\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#webpage\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/\",\"name\":\"EL PEZ JUGUET\\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret\",\"description\":\"EL PEZ JUGUET\\u00d3N de WISE, GRAHAM disponible a\\\/en Llibreria Claret.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/wp-content\\\/uploads\\\/.\\\/9788411821520.jpg\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#mainImage\",\"width\":250,\"height\":240,\"caption\":\"9788411821520.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/libro\\\/el-pez-jugueton-9788411821520\\\/#mainImage\"},\"datePublished\":\"2024-07-03T16:40:46+02:00\",\"dateModified\":\"2025-04-22T12:20:37+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/\",\"name\":\"Llibreria Claret Barcelona\",\"alternateName\":\"Llibreria Claret\",\"description\":\"Llibreria religiosa a Barcelona\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.claret.cat\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>EL PEZ JUGUET\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret<\/title>\n\n","aioseo_head_json":{"title":"EL PEZ JUGUET\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret","description":"EL PEZ JUGUET\u00d3N de WISE, GRAHAM disponible a\/en Llibreria Claret.","canonical_url":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"xVtlFxJ-TfkIu-D-lt7XeLobefg5EIQiXTuqcSf8Rf0","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.claret.cat\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","position":2,"name":"Botiga","item":"https:\/\/www.claret.cat\/?page_id=16","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","position":3,"name":"CAT","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/#listItem","name":"Infantil \/ Juvenil"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/?page_id=16#listItem","name":"Botiga"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/#listItem","position":4,"name":"Infantil \/ Juvenil","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/#listItem","name":"Infantil"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/#listItem","name":"CAT"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/#listItem","position":5,"name":"Infantil","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/contes-per-infants-0-6-anys\/#listItem","name":"0 - 6 anys"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/#listItem","name":"Infantil \/ Juvenil"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/contes-per-infants-0-6-anys\/#listItem","position":6,"name":"0 - 6 anys","item":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/contes-per-infants-0-6-anys\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#listItem","name":"EL PEZ JUGUET\u00d3N"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/#listItem","name":"Infantil"}},{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#listItem","position":7,"name":"EL PEZ JUGUET\u00d3N","previousItem":{"@type":"ListItem","@id":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/contes-per-infants-0-6-anys\/#listItem","name":"0 - 6 anys"}}]},{"@type":"ItemPage","@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#itempage","url":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/","name":"EL PEZ JUGUET\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret","description":"EL PEZ JUGUET\u00d3N de WISE, GRAHAM disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9788411821520.jpg","@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#mainImage","width":250,"height":240,"caption":"9788411821520.jpg"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#mainImage"},"datePublished":"2024-07-03T16:40:46+02:00","dateModified":"2025-04-22T12:20:37+02:00"},{"@type":"Organization","@id":"https:\/\/www.claret.cat\/es\/#organization","name":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","url":"https:\/\/www.claret.cat\/es\/","email":"comunicacio@claret.cat","telephone":"+34933010887","logo":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/logo-claret-es.png","@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#organizationLogo","width":195,"height":79},"image":{"@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/LlibreriaClaret","https:\/\/twitter.com\/LlibreriaClaret","https:\/\/www.instagram.com\/llibreriaclaret\/","https:\/\/www.tiktok.com\/@llibreriaclaret","https:\/\/www.youtube.com\/@llibreriaclaret","https:\/\/ca.wikipedia.org\/wiki\/Editorial_Claret"]},{"@type":"WebPage","@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#webpage","url":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/","name":"EL PEZ JUGUET\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret","description":"EL PEZ JUGUET\u00d3N de WISE, GRAHAM disponible a\/en Llibreria Claret.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.claret.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.claret.cat\/wp-content\/uploads\/.\/9788411821520.jpg","@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#mainImage","width":250,"height":240,"caption":"9788411821520.jpg"},"primaryImageOfPage":{"@id":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/#mainImage"},"datePublished":"2024-07-03T16:40:46+02:00","dateModified":"2025-04-22T12:20:37+02:00"},{"@type":"WebSite","@id":"https:\/\/www.claret.cat\/es\/#website","url":"https:\/\/www.claret.cat\/es\/","name":"Llibreria Claret Barcelona","alternateName":"Llibreria Claret","description":"Llibreria religiosa a Barcelona","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.claret.cat\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Llibreria Claret - Llibreria religiosa a Barcelona","og:type":"article","og:title":"EL PEZ JUGUET\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret","og:description":"EL PEZ JUGUET\u00d3N de WISE, GRAHAM disponible a\/en Llibreria Claret.","og:url":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/","og:image":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","og:image:secure_url":"https:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg","article:published_time":"2024-07-03T14:40:46+00:00","article:modified_time":"2025-04-22T10:20:37+00:00","article:publisher":"https:\/\/www.facebook.com\/LlibreriaClaret","twitter:card":"summary_large_image","twitter:site":"@LlibreriaClaret","twitter:title":"EL PEZ JUGUET\u00d3N - WISE, GRAHAM 9788411821520 | Llibreria Claret","twitter:description":"EL PEZ JUGUET\u00d3N de WISE, GRAHAM disponible a\/en Llibreria Claret.","twitter:image":"http:\/\/dev.claret.cat\/wp-content\/uploads\/logo-claret.svg"},"aioseo_meta_data":{"post_id":"973221","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-09 21:08:14","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2024-07-03 14:53:09","updated":"2026-06-09 21:08:14","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/es\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/?page_id=16\" title=\"Botiga\">Botiga<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/\" title=\"CAT\">CAT<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/\" title=\"Infantil \/ Juvenil\">Infantil \/ Juvenil<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/\" title=\"Infantil\">Infantil<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/contes-per-infants-0-6-anys\/\" title=\"0 - 6 anys\">0 - 6 anys<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tEL PEZ JUGUET\u00d3N\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.claret.cat\/es\/"},{"label":"Botiga","link":"https:\/\/www.claret.cat\/?page_id=16"},{"label":"CAT","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/"},{"label":"Infantil \/ Juvenil","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/"},{"label":"Infantil","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/"},{"label":"0 - 6 anys","link":"https:\/\/www.claret.cat\/categoria-producto\/cat\/3_infantil-juvenil\/infantil\/contes-per-infants-0-6-anys\/"},{"label":"EL PEZ JUGUET\u00d3N","link":"https:\/\/www.claret.cat\/es\/libro\/el-pez-jugueton-9788411821520\/"}],"_links":{"self":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product\/973221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media\/973222"}],"wp:attachment":[{"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/media?parent=973221"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_brand?post=973221"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_cat?post=973221"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.claret.cat\/es\/wp-json\/wp\/v2\/product_tag?post=973221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}